{"id":759,"date":"2017-04-14T13:51:59","date_gmt":"2017-04-14T11:51:59","guid":{"rendered":"http:\/\/www.courdescomptes.sn\/?p=759"},"modified":"2018-01-03T16:37:57","modified_gmt":"2018-01-03T15:37:57","slug":"directive-n0597cmuemoa-relative-aux-lois-de-finances","status":"publish","type":"post","link":"https:\/\/www.courdescomptes.sn\/en\/directive-n0597cmuemoa-relative-aux-lois-de-finances\/","title":{"rendered":"(FR) Directive n\u00b005\/97\/CM\/UEMOA relative aux lois de finances"},"content":{"rendered":"<p class=\"qtranxs-available-languages-message qtranxs-available-languages-message-en\">Sorry, this entry is only available in <a href=\"https:\/\/www.courdescomptes.sn\/fr\/wp-json\/wp\/v2\/posts\/759\" class=\"qtranxs-available-language-link qtranxs-available-language-link-fr\" title=\"FR\">French<\/a>.<\/p>","protected":false},"excerpt":{"rendered":"<p>Sorry, this entry is only available in French.<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[23],"tags":[],"_links":{"self":[{"href":"https:\/\/www.courdescomptes.sn\/en\/wp-json\/wp\/v2\/posts\/759"}],"collection":[{"href":"https:\/\/www.courdescomptes.sn\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.courdescomptes.sn\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.courdescomptes.sn\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.courdescomptes.sn\/en\/wp-json\/wp\/v2\/comments?post=759"}],"version-history":[{"count":3,"href":"https:\/\/www.courdescomptes.sn\/en\/wp-json\/wp\/v2\/posts\/759\/revisions"}],"predecessor-version":[{"id":1052,"href":"https:\/\/www.courdescomptes.sn\/en\/wp-json\/wp\/v2\/posts\/759\/revisions\/1052"}],"wp:attachment":[{"href":"https:\/\/www.courdescomptes.sn\/en\/wp-json\/wp\/v2\/media?parent=759"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.courdescomptes.sn\/en\/wp-json\/wp\/v2\/categories?post=759"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.courdescomptes.sn\/en\/wp-json\/wp\/v2\/tags?post=759"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}